{"id":17157,"date":"2022-01-28T16:53:11","date_gmt":"2022-01-28T16:53:11","guid":{"rendered":"https:\/\/temp6.xprss-sandbox.com\/?page_id=17157"},"modified":"2023-10-10T18:47:50","modified_gmt":"2023-10-10T18:47:50","slug":"financement","status":"publish","type":"page","link":"https:\/\/www.timminsrv.com\/fr\/financement\/","title":{"rendered":"Financement"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"17157\" class=\"elementor elementor-17157 elementor-9784\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f8271b6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f8271b6\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[],&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-911065f\" data-id=\"911065f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6fab9a0 elementor-widget elementor-widget-jet-listing-dynamic-field\" data-id=\"6fab9a0\" data-element_type=\"widget\" data-widget_type=\"jet-listing-dynamic-field.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"jet-listing jet-listing-dynamic-field display-inline\"><div class=\"jet-listing-dynamic-field__inline-wrap\"><h1 class=\"jet-listing-dynamic-field__content\">Financement<\/h1><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-f362da1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f362da1\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[],&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-80ad0c3\" data-id=\"80ad0c3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b9252f9 elementor-widget elementor-widget-heading\" data-id=\"b9252f9\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Options de financement faciles pour votre VR<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8696dd0 elementor-widget elementor-widget-image-carousel\" data-id=\"8696dd0\" data-element_type=\"widget\" data-settings=\"{&quot;navigation&quot;:&quot;none&quot;,&quot;autoplay&quot;:&quot;no&quot;,&quot;infinite&quot;:&quot;no&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carrousel d\u2019images\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"polite\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 sur 3\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.timminsrv.com\/wp-content\/smush-webp\/2022\/05\/logo-desjardins.png.webp\" alt=\"DesJardins Bank\" data-smush-webp-fallback=\"{&quot;src&quot;:&quot;https:\\\/\\\/www.timminsrv.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/logo-desjardins.png&quot;}\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 sur 3\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.timminsrv.com\/wp-content\/smush-webp\/2022\/05\/logo-national-bank.jpg.webp\" alt=\"National Bank of Canada (CNW Group\/National Bank of Canada)\" data-smush-webp-fallback=\"{&quot;src&quot;:&quot;https:\\\/\\\/www.timminsrv.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/logo-national-bank.jpg&quot;}\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 sur 3\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.timminsrv.com\/wp-content\/smush-webp\/2022\/05\/logo-td.jpg.webp\" alt=\"TD Canada Trust Bank\" data-smush-webp-fallback=\"{&quot;src&quot;:&quot;https:\\\/\\\/www.timminsrv.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/logo-td.jpg&quot;}\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-89aac96 elementor-widget elementor-widget-text-editor\" data-id=\"89aac96\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>VR Timmins est affili\u00e9 \u00e0 plusieurs pr\u00eateurs sp\u00e9cialis\u00e9s qui offrent d&rsquo;excellents taux d&rsquo;int\u00e9r\u00eat et des modalit\u00e9s de paiement souples, qui peuvent aller jusqu&rsquo;\u00e0 240 mois sur les nouvelles unit\u00e9s. Notre personnel financier interne peut vous aider \u00e0 prendre des d\u00e9cisions de financement ajust\u00e9es \u00e0 votre revenu.<\/p><p>Nous vous aiderons \u00e0 d\u00e9terminer les meilleures options de financement disponibles. Votre nouvel achat est important pour nous, mais le plus important pour nous est de savoir que nous avons fourni le meilleur produit, avec la meilleure option de financement possible.<\/p><p>Lorsque vous magasinez pour un v\u00e9hicule r\u00e9cr\u00e9atif, quel qu&rsquo;il soit, votre priorit\u00e9 devrait \u00eatre de trouver le type de v\u00e9hicule qui convient \u00e0 vos d\u00e9sirs et \u00e0 vos besoins. Cependant, si vous magasinez uniquement en fonction du prix, nous avons de nombreuses options dans notre vaste s\u00e9lection de VR d&rsquo;occasion de qualit\u00e9 qui vous feront faire des \u00e9conomies consid\u00e9rables.<\/p><p>Notre personnel expert peut r\u00e9pondre \u00e0 toutes vos questions et vous aider \u00e0 choisir une unit\u00e9 de qualit\u00e9 qui r\u00e9pond \u00e0 vos besoins et \u00e0 votre budget. Nous proposons \u00e9galement les programmes suivants pour prot\u00e9ger votre nouvel investissement, vous-m\u00eame et surtout votre famille :<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8cb17e4 elementor-widget elementor-widget-heading\" data-id=\"8cb17e4\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Contrats de garantie prolong\u00e9e<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-455e952 elementor-widget elementor-widget-text-editor\" data-id=\"455e952\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Offrez \u00e0 vous et \u00e0 votre famille la tranquillit\u00e9 d&rsquo;esprit, assurez-vous que votre VR est couvert par l&rsquo;un de nos contrats.<\/p>\n<ul>\n<li>Vous offre une protection lorsque vous en avez le plus besoin<\/li>\n<li>La protection dont vous avez besoin contre les factures de r\u00e9paration inattendues<\/li>\n<li>Services disponibles partout en Am\u00e9rique du Nord<\/li>\n<li>Jusqu&rsquo;\u00e0 sept ans de contrats disponibles sur les nouveaux VR<\/li>\n<li>Conditions flexibles adapt\u00e9es \u00e0 vos besoins<\/li>\n<li>Jusqu&rsquo;\u00e0 quatre ans de contrats disponibles pour les unit\u00e9s de moins de 10 ans<\/li>\n<li>Pour obtenir le meilleur rapport qualit\u00e9-prix, VR Timmins recommande le contrat de sept ans.<\/li>\n<\/ul>\n<p>Protection des pr\u00eats\/paiements \u2013 Stabilit\u00e9<\/p>\n<ul>\n<li>Prot\u00e8ge votre famille en cas de d\u00e9c\u00e8s (Actif vs Passif)<\/li>\n<li>S&rsquo;assure que vos paiements sont effectu\u00e9s en cas de maladie et d&rsquo;incapacit\u00e9 de travail<\/li>\n<li>Diff\u00e9rents programmes disponibles de 10 $ \u00e0 40 $ par personne, par mois<\/li>\n<\/ul>\n<div>&nbsp;<\/div>\n<p><strong>T\u00e9l\u00e9charger les brochures de Garanties Prolong\u00e9es<\/strong><\/p>\n<p><a href=\"\/wp-content\/uploads\/2023\/02\/extended-warranty-travel-trailers-EN.pdf\" target=\"_blank\" rel=\"noopener\">Brochure sur la garantie prolong\u00e9e &#8211; Roulottes <span class=\"sr-only\">Ce lien s&rsquo;ouvre dans une nouvelle fen\u00eatre<\/span><\/a><span class=\"small\">[PDF : 733Ko, disponible en anglais uniquement]<\/span><\/p>\n<p><a href=\"\/wp-content\/uploads\/2023\/02\/extended-warranty-motorhomes-EN.pdf\" target=\"_blank\" rel=\"noopener\">Brochure Garantie prolong\u00e9e &#8211; Motoris\u00e9s<span class=\"sr-only\">Ce lien s&rsquo;ouvre dans une nouvelle fen\u00eatre<\/span><\/a> <span class=\"small\">[PDF : 2Mo, disponible en anglais uniquement]<\/span><\/p>\n<p><strong>Avantages de la garantie prolong\u00e9e<\/strong><\/p>\n<p>Voici quelques-uns des avantages qui peuvent venir avec notre garantie prolong\u00e9e lorsque vous remplissez les conditions d&rsquo;\u00e9ligibilit\u00e9.<\/p>\n<ul>\n<li>Assistance sur place disponible pour les VR qui r\u00e9sident sur un terrain de camping pendant plus de deux mois (\u00e0 l&rsquo;exclusion des motoris\u00e9s)<\/li>\n<li>Transf\u00e9rabilit\u00e9 \u2013 toute couverture inutilis\u00e9e est transf\u00e9rable<\/li>\n<li>Indemnisation pour la d\u00e9t\u00e9rioration des aliments due \u00e0 une panne de r\u00e9frig\u00e9rateur.<\/li>\n<\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5cc4fee elementor-widget elementor-widget-heading\" data-id=\"5cc4fee\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Protection des pr\u00eats et des paiements<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6eb18e1 elementor-widget elementor-widget-text-editor\" data-id=\"6eb18e1\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Cette protection vous offre la tranquillit\u00e9 d&rsquo;esprit en cas de perte de salaire<\/p>\n<ul>\n<li>La vie<\/li>\n<li>Maladie critique<\/li>\n<li>Accident et maladie<\/li>\n<li>Ch\u00f4mage involontaire<\/li>\n<\/ul>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-35942e5 elementor-widget elementor-widget-heading\" data-id=\"35942e5\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">L'avantage Companion Gap<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9c4042f elementor-widget elementor-widget-text-editor\" data-id=\"9c4042f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Non disponible pour les r\u00e9sidents du Qu\u00e9bec<\/p><p><a href=\"\/wp-content\/uploads\/2023\/02\/companion-gap-brochure.pdf\" target=\"_blank\" rel=\"noopener\">Brochure Companion Gap Advantage <span class=\"sr-only\">Ce lien s&rsquo;ouvrira dans une nouvelle fen\u00eatre<\/span><\/a> <span class=\"small\">[PDF : 5 Mo, disponible en anglais uniquement<\/span>]<\/p><ul><li>Vous prot\u00e8ge des fonds propres n\u00e9gatifs et de la d\u00e9pr\u00e9ciation du VR<\/li><li>Offre une couverture sur de nombreux VR neufs ou d&rsquo;occasion<\/li><li>Jusqu&rsquo;\u00e0 sept ans de protection<\/li><li>Couverture du d\u00e9ficit<\/li><li>Couverture pour les VR dont le prix d&rsquo;achat est de 150\u00a0000\u00a0$ ou moins<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-cfc3d64\" data-id=\"cfc3d64\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3c32aa4 elementor-widget elementor-widget-heading\" data-id=\"3c32aa4\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Contactez-nous pour plus d'informations sur le financement<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6ff4456 elementor-widget elementor-widget-jet-engine-booking-form\" data-id=\"6ff4456\" data-element_type=\"widget\" data-widget_type=\"jet-engine-booking-form.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"formulaire-container-26985\" class=\"jfb-form-marker\"><\/div>    <script>\n    document.addEventListener('DOMContentLoaded', function () {\n        const markerId = 'formulaire-container-26985';\n        console.log('[JFB] DOM ready. Looking for marker:', markerId);\n\n        const marker = document.getElementById(markerId);\n        if (!marker) {\n            console.warn('[JFB] Marker not found:', markerId);\n            return;\n        }\n        console.log('[JFB] Marker found:', marker);\n\n        \/\/ Prefer next sibling if it's a form, fallback to parent query\n        let form = (marker.nextElementSibling && marker.nextElementSibling.tagName === 'FORM')\n            ? marker.nextElementSibling\n            : (marker.parentElement ? marker.parentElement.querySelector('form') : null);\n\n        if (!form) {\n            console.warn('[JFB] Form not found near marker:', markerId);\n            return;\n        }\n        console.log('[JFB] Form found:', form);\n\n        const formIdInput = form.querySelector('input[type=\"hidden\"][name=\"form_id\"]');\n        if (!formIdInput) {\n            console.warn('[JFB] Hidden input form_id not found in form:', form);\n            return;\n        }\n        console.log('[JFB] form_id input found:', formIdInput);\n\n        const formIdValue = (formIdInput.value || '').trim();\n        if (!formIdValue) {\n            console.warn('[JFB] form_id value is empty for marker:', markerId);\n            return;\n        }\n        console.log('[JFB] form_id value:', formIdValue);\n\n        \/\/ If needed, customize prefix based on dealer logic\n        \/\/ const newId = 'camp_' + formIdValue;\n        const newId = formIdValue;\n\n        form.id = newId;\n        console.log('[JFB] Form ID assigned successfully:', newId, form);\n    });\n    <\/script>\n    <style id=\"jet-form-builder-26985-inline-css\"><\/style><form  class=\"jet-form-builder layout-column submit-type-ajax\" action=\"https:\/\/www.timminsrv.com\/fr\/wp-json\/wp\/v2\/pages\/17157\/?jet_form_builder_submit=submit&amp;method=reload\" method=\"POST\" data-form-id=\"26985\" data-layout=\"column\" enctype=\"multipart\/form-data\" novalidate=\"null\">\r\n<input type=\"hidden\" name=\"_jfb_current_render_states[]\" value=\"DEFAULT.STATE\" data-jfb-sync \/><input type=\"hidden\" class=\"jet-form-builder__field hidden-field\" name=\"_jet_engine_booking_form_id\" data-field-name=\"_jet_engine_booking_form_id\" value=\"26985\">\n<input type=\"hidden\" class=\"jet-form-builder__field hidden-field\" name=\"_jet_engine_refer\" data-field-name=\"_jet_engine_refer\" value=\"https:\/\/www.timminsrv.com\/fr\/wp-json\/wp\/v2\/pages\/17157\/\">\n<input type=\"hidden\" class=\"jet-form-builder__field hidden-field\" name=\"__queried_post_id\" data-field-name=\"__queried_post_id\" value=\"17157\">\n\n\n\n<input type=\"hidden\" class=\"jet-form-builder__field hidden-field\" name=\"form_id\" data-field-name=\"form_id\" data-jfb-sync=\"null\" value=\"page_financing_fr\">\n\n\n\n\n\n\n\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><div  class=\"jet-form-builder-row field-type-text-field\" >\n<div class=\"jet-form-builder__label\">\r\n<div class=\"jet-form-builder__label-text\">Pr\u00e9nom <span class=\"jet-form-builder__required\">*<\/span><\/div><\/div><div class=\"jet-form-builder__field-wrap\">\n\t\t\t\t<input required=\"required\" name=\"field_firstname\" id=\"field_firstname\" type=\"text\" data-field-name=\"field_firstname\" class=\"jet-form-builder__field text-field\" maxlength=\"50\" data-jfb-sync=\"null\" autocomplete=\"off_ZfwuOD0R\">\n\t\t\t\t\t<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><div  class=\"jet-form-builder-row field-type-text-field\" >\n<div class=\"jet-form-builder__label\">\r\n<div class=\"jet-form-builder__label-text\">Nom <span class=\"jet-form-builder__required\">*<\/span><\/div><\/div><div class=\"jet-form-builder__field-wrap\">\n\t\t\t\t<input required=\"required\" name=\"field_lastname\" id=\"field_lastname\" type=\"text\" data-field-name=\"field_lastname\" class=\"jet-form-builder__field text-field\" maxlength=\"50\" data-jfb-sync=\"null\" autocomplete=\"off_Xhs5wZn8\">\n\t\t\t\t\t<\/div>\n<\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><div  class=\"jet-form-builder-row field-type-text-field\" >\n<div class=\"jet-form-builder__label\">\r\n<div class=\"jet-form-builder__label-text\">Courriel <span class=\"jet-form-builder__required\">*<\/span><\/div><\/div><div class=\"jet-form-builder__field-wrap\">\n\t\t\t\t<input required=\"required\" name=\"field_mail\" id=\"field_mail\" type=\"email\" data-field-name=\"field_mail\" class=\"jet-form-builder__field text-field\" maxlength=\"62\" data-jfb-sync=\"null\" autocomplete=\"off_EobdWhGX\">\n\t\t\t\t\t<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><div  class=\"jet-form-builder-row field-type-text-field\" >\n<div class=\"jet-form-builder__label\">\r\n<div class=\"jet-form-builder__label-text\">T\u00e9l\u00e9phone <span class=\"jet-form-builder__required\">*<\/span><\/div><\/div><div class=\"jet-form-builder__field-wrap\">\n\t\t\t\t<input required=\"required\" name=\"field_phone\" id=\"field_phone\" type=\"tel\" data-field-name=\"field_phone\" class=\"jet-form-builder__field text-field\" maxlength=\"13\" data-jfb-sync=\"null\" autocomplete=\"off_5AwnlpdU\">\n\t\t\t\t\t<\/div>\n<\/div><\/div>\n<\/div>\n\n\n<div  class=\"jet-form-builder-row field-type-textarea-field\" >\n<div class=\"jet-form-builder__label\">\r\n<div class=\"jet-form-builder__label-text\">Message <span class=\"jet-form-builder__required\">*<\/span><\/div><\/div><div class=\"jet-form-builder__field-wrap\">\n\t\t<textarea class=\"jet-form-builder__field textarea-field\" required=\"required\" name=\"field_message\" data-field-name=\"field_message\" id=\"field_message\" data-jfb-sync=\"null\"><\/textarea>\n\t<\/div><div class=\"jet-form-builder__desc\"><small>Longueur max 300 caract\u00e8res<\/small><\/div>\n<\/div>\n\n<input type=\"hidden\" class=\"captcha-token\" name=\"_captcha_token\" value=\"\"\/><div  class=\"jet-form-builder-row field-type-submit-field\" >\n\t<div data-type=\"submit\" class=\"jet-form-builder__action-button-wrapper jet-form-builder__submit-wrap\">\n\t<button class=\"jet-form-builder__action-button jet-form-builder__submit submit-type-ajax\" type=\"submit\">Envoyer la demande<\/button>\n\t<\/div>\n\t\n<\/div>\t<div class=\"jet-form-builder-messages-wrap\" data-form-id=\"26985\"><\/div>\n<\/form>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d3a9003 elementor-widget elementor-widget-heading\" data-id=\"d3a9003\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Forfaits de protection<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1f278e0 elementor-widget elementor-widget-image\" data-id=\"1f278e0\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"84\" src=\"https:\/\/www.timminsrv.com\/wp-content\/smush-webp\/2022\/05\/DiamonKoteLogo.png.webp\" class=\"attachment-large size-large wp-image-23832\" alt=\"\" srcset=\"https:\/\/www.timminsrv.com\/wp-content\/smush-webp\/2022\/05\/DiamonKoteLogo.png.webp 1023w, https:\/\/www.timminsrv.com\/wp-content\/smush-webp\/2022\/05\/DiamonKoteLogo-300x31.png.webp 300w, https:\/\/www.timminsrv.com\/wp-content\/smush-webp\/2022\/05\/DiamonKoteLogo-600x63.png.webp 600w, https:\/\/www.timminsrv.com\/wp-content\/smush-webp\/2022\/05\/DiamonKoteLogo-768x80.png.webp 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" data-smush-webp-fallback=\"{&quot;src&quot;:&quot;https:\\\/\\\/www.timminsrv.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/DiamonKoteLogo.png&quot;,&quot;srcset&quot;:&quot;https:\\\/\\\/www.timminsrv.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/DiamonKoteLogo.png 1023w, https:\\\/\\\/www.timminsrv.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/DiamonKoteLogo-300x31.png 300w, https:\\\/\\\/www.timminsrv.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/DiamonKoteLogo-600x63.png 600w, https:\\\/\\\/www.timminsrv.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/DiamonKoteLogo-768x80.png 768w&quot;}\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2d7c246 elementor-widget elementor-widget-text-editor\" data-id=\"2d7c246\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Nous offrons une protection contre les \u00e9l\u00e9ments gr\u00e2ce \u00e0 nos plans de protection Diamond Kote\u00ae. Une vari\u00e9t\u00e9 d&rsquo;options sont disponibles pour r\u00e9pondre \u00e0 vos besoins.<\/p><ul><li>Protection de la peinture<\/li><li>Protection des tissus &#8211; Protection cuir\/vinyle<\/li><li>Pneus et jantes Pro<\/li><\/ul><div>\u00a0<\/div><p><strong><br \/>Protection de peinture Diamond Kote<sup>\u00ae<\/sup><\/strong><\/p><p>La protection ext\u00e9rieure de Diamond Kote adh\u00e8re \u00e0 la surface de votre VR et prot\u00e8ge contre la perte de brillance, le sel de voirie, la s\u00e8ve des arbres, le goudron de route, les fientes d&rsquo;oiseaux, les pluies acides et la pollution. Diamond Kote\u00ae offre une protection \u00ab\u00a0tranquillit\u00e9 d&rsquo;esprit\u00a0\u00bb pour votre VR. Pr\u00e9venez les dommages caus\u00e9s par les polluants environnementaux qui peuvent d\u00e9truire la finition de votre VR.<\/p><p><strong>Protection Diamond Kote<sup>\u00ae<\/sup>\u00a0Prot\u00e8ge-Tissu ainsi que Prot\u00e8ge-Cuir\/Vinyle<\/strong><\/p><p>Notre Prot\u00e8ge-Tissu p\u00e9n\u00e8tre profond\u00e9ment dans le tissu, formant un bouclier invisible autour de chaque fibre. Ce rev\u00eatement protecteur emp\u00eache la p\u00e9n\u00e9tration de d\u00e9versements tels que le caf\u00e9, le th\u00e9, le lait, les boissons gazeuses et les aliments sans affecter la texture naturelle du tissu.<\/p><p>Le Prot\u00e8ge-Cuir\/Vinyle Diamond Kote<sup>\u00ae<\/sup>\u00a0utilise une formule unique, naturelle, semi-perm\u00e9able et \u00e0 base d&rsquo;eau qui prot\u00e8ge le cuir et le vinyle int\u00e9rieurs, emp\u00eachant la plupart des taches de p\u00e9n\u00e9trer, permettant un nettoyage rapide et facile. Cette chimie unique permet au cuir de respirer naturellement et de maintenir l&rsquo;\u00e9quilibre d&rsquo;humidit\u00e9 naturel n\u00e9cessaire pour assurer une finition lisse et souple pendant longtemps.<\/p><p><strong>Pneus et jantes Diamond Kote<sup>\u00ae<\/sup> Pro<\/strong><\/p><p>La protection des pneus et des jantes offre une couverture pour les pneus ordinaires et remplis d&rsquo;azote en cas de dommages impr\u00e9vus. En cas de dommages dus aux al\u00e9as de la route, vos pneus ou jantes seront remplac\u00e9s par des pneus de m\u00eame qualit\u00e9.<\/p><p><strong>Caract\u00e9ristiques :<\/strong><\/p><ul><li>Couverture compl\u00e8te des pneus et jantes toutes saisons et d&rsquo;hiver<\/li><li>Couverture de crevaison<\/li><li>Remplacement des pneus<\/li><li>Protection des roues et des jantes<\/li><li>Nourriture et h\u00e9bergement<\/li><li>Assistance routi\u00e8re<\/li><li>Remorquage<\/li><li>Dommages en bordure de rue<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Financement Options de financement faciles pour votre VR VR Timmins est affili\u00e9 \u00e0 plusieurs pr\u00eateurs sp\u00e9cialis\u00e9s qui offrent d&rsquo;excellents taux d&rsquo;int\u00e9r\u00eat et des modalit\u00e9s de paiement souples, qui peuvent aller jusqu&rsquo;\u00e0 240 mois sur les nouvelles unit\u00e9s. Notre personnel financier interne peut vous aider \u00e0 prendre des d\u00e9cisions de financement ajust\u00e9es \u00e0 votre revenu. Nous [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":11793,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-17157","page","type-page","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/www.timminsrv.com\/fr\/wp-json\/wp\/v2\/pages\/17157","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.timminsrv.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.timminsrv.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.timminsrv.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.timminsrv.com\/fr\/wp-json\/wp\/v2\/comments?post=17157"}],"version-history":[{"count":0,"href":"https:\/\/www.timminsrv.com\/fr\/wp-json\/wp\/v2\/pages\/17157\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.timminsrv.com\/fr\/wp-json\/wp\/v2\/media\/11793"}],"wp:attachment":[{"href":"https:\/\/www.timminsrv.com\/fr\/wp-json\/wp\/v2\/media?parent=17157"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}